{"id":68994,"date":"2022-01-05T00:00:00","date_gmt":"2022-01-05T00:00:00","guid":{"rendered":"https:\/\/chicagodesavanja.us\/venue\/sigma-design-center\/"},"modified":"2022-01-05T00:00:00","modified_gmt":"2022-01-05T00:00:00","slug":"sigma-design-center","status":"publish","type":"ivp_venue","link":"https:\/\/chicagodesavanja.us\/en\/mesta\/sigma-design-center\/","title":{"rendered":"Sigma Design Center"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","locations":[],"class_list":["post-68994","ivp_venue","type-ivp_venue","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/venues\/68994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/venues"}],"about":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/types\/ivp_venue"}],"wp:attachment":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/media?parent=68994"}],"wp:term":[{"taxonomy":"ivp_location","embeddable":true,"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/locations?post=68994"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}