{"id":61136,"count":1,"description":"","link":"https:\/\/chicagodesavanja.us\/en\/vesti\/tag\/univerzitet-purdue\/","name":"Univerzitet Purdue","slug":"univerzitet-purdue","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/tags\/61136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/posts?tags=61136"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}