{"id":21524,"count":1,"description":"","link":"https:\/\/chicagodesavanja.us\/en\/vesti\/tag\/mrs-hering-s-chicken-pot-pie\/","name":"Mrs. Hering\u2019s chicken pot pie","slug":"mrs-hering-s-chicken-pot-pie","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/tags\/21524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chicagodesavanja.us\/en\/wp-json\/wp\/v2\/posts?tags=21524"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}